{"id":5791,"date":"2022-05-30T22:58:47","date_gmt":"2022-05-30T21:58:47","guid":{"rendered":"https:\/\/www.plantopia.me\/?post_type=product&#038;p=5791"},"modified":"2024-10-21T01:34:05","modified_gmt":"2024-10-21T00:34:05","slug":"lombricomposteur","status":"publish","type":"product","link":"https:\/\/www.plantopia.me\/ar\/produits\/lombricomposteur\/","title":{"rendered":"Kit Lombricomposteur Urbain"},"content":{"rendered":"<p>Kit \u00ab\u00a0Lombricomposteur urbain\u00a0\u00bb \u00e0 \u00e9tages. Livraison partout au Maroc.<\/p>\n<ul>\n<li>Hauteur : 60,5 cm<\/li>\n<li>Largeur : 50,5 cm<\/li>\n<li>Profondeur : 38 cm<\/li>\n<li>Haute qualit\u00e9<\/li>\n<li>Mat\u00e9riau non pourrissable (Contrairement au bois)<\/li>\n<li>Look \u00e9l\u00e9gant<\/li>\n<li>Utilisable \u00e0 l&rsquo;int\u00e9rieur comme \u00e0 l&rsquo;ext\u00e9rieur<\/li>\n<li>Avec purgeur de th\u00e9 de lombricompost<\/li>\n<li>Pratique &amp; fonctionnel<\/li>\n<li>Couleur : Bronze<\/li>\n<li>Le kit est vendu sans vers de terre<\/li>\n<li>Installation facile (Guide fournie)<\/li>\n<\/ul>\n<h4 style=\"text-align: center;\"><strong><span style=\"font-size: 115%;\">\ud83d\udc4d Bon \u00e0 savoir :<\/span><\/strong><\/h4>\n<p><span style=\"color: #333333;\">\ud83d\ude0b<\/span>Vous obtiendrez un engrais organique de haute qualit\u00e9 pour la culture de plantes d&rsquo;int\u00e9rieur et d&rsquo;ext\u00e9rieur.<br \/>\n<span class=\"pq6dq46d tbxw36s4 knj5qynh kvgmc6g5 ditlmg2l oygrvhab nvdbi5me sf5mxxl7 gl3lb2sf hhz5lgdu\"><img decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/td7\/1.5\/16\/1f52c.png\" alt=\"\ud83d\udd2c\" width=\"16\" height=\"16\" \/><\/span>Le <a href=\"https:\/\/www.plantopia.me\/fr\/produit\/lombricompost-maroc-10l\/\"><strong>vermicompost<\/strong><\/a> contient des enzymes puissantes et des hormones de croissance naturelles. Il peut \u00eatre ajout\u00e9 au jardin, dans des pots de fleurs et des jardini\u00e8res. Le <a href=\"https:\/\/www.plantopia.me\/fr\/produit\/lombrithe-lombriliquide-1l\/\"><strong>lombrith\u00e9<\/strong><\/a> est un engrais liquide contenant beaucoup de nutriments riches et d&rsquo;enzymes qui aident vos plantes \u00e0 se d\u00e9velopper, les rendre plus r\u00e9sistantes et \u00e0 les immuniser contre les parasites<br \/>\n<span style=\"color: #333333;\">\ud83d\udc49<\/span>Ce lombricomposteur est une pi\u00e8ce de design r\u00e9compens\u00e9e \u00e0 la fois par le RedDot Design Award et le Good Design.<\/p>","protected":false},"excerpt":{"rendered":"<p>Kit Lombricomposteur d&rsquo;int\u00e9rieur et d&rsquo;ext\u00e9rieur au Maroc.<\/p>\n<p>Ce lombricomposteur de haute qualit\u00e9 vous permet de transformer rapidement, efficacement, et proprement vos restes de cuisine en vermicompost \/ lombricompost riche et nutritif.<br \/>\nIl peut \u00eatre utilis\u00e9 \u00e0 la maison, \u00e0 l&rsquo;\u00e9cole ou au bureau, \u00e0 l&rsquo;int\u00e9rieur ou \u00e0 l&rsquo;ext\u00e9rieur. Son design fait de lui un meuble tr\u00e8s \u00e9l\u00e9gant.<br \/>\nLe compostage dans ce lombricomposteur est <b>facile et sans odeur<\/b>, il vous suffit de suivre les r\u00e8gles de base. Le kit est livr\u00e9 avec des plateaux o\u00f9 les vers transforment les restes de nourriture en vermicompost, un bac o\u00f9 le th\u00e9 liquide est collect\u00e9 et un couvercle herm\u00e9tique.<br \/>\nImport\u00e9 d&rsquo;Europe, il est fabriqu\u00e9 \u00e0 base de mat\u00e9riau non pourrissable, contrairement aux lombricomposteurs de bois, qui pourrissent au contact prolong\u00e9 de l&rsquo;humidit\u00e9.<br \/>\nBref, un lombricomposteur au look moderne, pratique et de haute qualit\u00e9.<\/p>","protected":false},"featured_media":8316,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[30],"product_tag":[],"class_list":["post-5791","product","type-product","status-publish","has-post-thumbnail","product_cat-outils-arrosage","product_shipping_class-extra-heavyduty","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/product\/5791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/comments?post=5791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/media\/8316"}],"wp:attachment":[{"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/media?parent=5791"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/product_brand?post=5791"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/product_cat?post=5791"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/product_tag?post=5791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}