{"id":8703,"date":"2024-12-22T04:55:31","date_gmt":"2024-12-22T03:55:31","guid":{"rendered":"https:\/\/www.plantopia.me\/?post_type=product&#038;p=8703"},"modified":"2024-12-22T22:08:53","modified_gmt":"2024-12-22T21:08:53","slug":"engrais-naturel-seaweed-plantes-en-pot-4l","status":"publish","type":"product","link":"https:\/\/www.plantopia.me\/ar\/produits\/engrais-naturel-seaweed-plantes-en-pot-4l\/","title":{"rendered":"Engrais naturel \u00ab\u00a0Seaweed\u00a0\u00bb &#8211; 4L"},"content":{"rendered":"<p>Engrais fertilisant 100% naturel \u00ab\u00a0Algues marines\u00a0\u00bb. Livraison partout au Maroc.<\/p>\n<ul>\n<li>Granulation fine pour une action rapide<\/li>\n<li>Universel : Pour toutes les plantes (plantes d&rsquo;int\u00e9rieur, l\u00e9gumes, fleurs, herbes aromatiques, arbres et arbustes)<\/li>\n<li>Pour culture en pot et en pleine terre<\/li>\n<li>Utilisable toute l&rsquo;ann\u00e9e<\/li>\n<li>Entier :\u00a0Apporte des \u00e9l\u00e9ments nutritifs qui contribuent \u00e0 une croissance saine et vigoureuse des v\u00e9g\u00e9taux<\/li>\n<li>Augmente la r\u00e9tention en eau et en \u00e9l\u00e9ments nutritifs<\/li>\n<li>Composition : Extrait d&rsquo;algues 80% avec traces de 50 min\u00e9raux, cellulose du bois 20%<\/li>\n<li>Contient les traces de 50 min\u00e9raux, polysaccharides, acides amin\u00e9s, acides organiques, humates, auxines, cytokines et giberlins<\/li>\n<li>100% naturel (Ne contient : aucune boue d\u2019\u00e9gout aucun produit de synth\u00e8se)<\/li>\n<li>Pr\u00eat \u00e0 l&#8217;emploi : 1 \u00e0 2 Poign\u00e9es par plante \/\/ 250 gr par arbre ou arbuste<\/li>\n<li>Volume : 4 Litres<\/li>\n<\/ul>\n<h3 style=\"text-align: center;\"><strong>\ud83d\udc4dBon \u00e0 savoir :\u00a0<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Les algues ferment\u00e9s am\u00e9liorent tous les aspects des plantes, des fruits et l\u00e9gumes, du gazon et des herbes. Elles sont b\u00e9n\u00e9fiques pour :<\/p>\n<ul>\n<li>Acc\u00e9l\u00e9rer la croissance des plantes.<\/li>\n<li>Stimuler des floraisons spectaculaires<\/li>\n<li>Renforcer le syst\u00e8me immunitaire des plantes<\/li>\n<li>Intensifier la coloration des fruits et l\u00e9gumes.<\/li>\n<li>Am\u00e9liorer la qualit\u00e9, la quantit\u00e9, la vigueur et la conservation des r\u00e9coltes.<\/li>\n<li>Enrichir le sol\/terreau avec plus de 60 oligo-\u00e9l\u00e9ments essentiels.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><strong>Engrais 100% naturel<\/strong> compos\u00e9 d&rsquo;algues marines laminaires sous forme de poudre, tr\u00e8s riche en oligo-\u00e9l\u00e9ments et en compos\u00e9s organiques.<\/p>\n<p>Cet engrais contient les traces de 50 min\u00e9raux, polysaccharides, acides amin\u00e9s, acides organiques, humates, auxines, cytokines et giberlins<\/p>\n<p>Tr\u00e8s bon engrais de fond naturel pour les plantes pot, le jardin d&rsquo;ornement, potager et verger, obtenu de la fermentation naturelle de diff\u00e9rentes algues marines.<\/p>\n<p>Les algues marines favorisent la germination et la croissance des plantes, stimulent leurs d\u00e9fenses naturelles et reconstituent le sol \/ terreau.<\/p>","protected":false},"featured_media":8709,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[28,27],"product_tag":[],"class_list":["post-8703","product","type-product","status-publish","has-post-thumbnail","product_cat-bio-organique","product_cat-engrais","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/product\/8703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/comments?post=8703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/media\/8709"}],"wp:attachment":[{"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/media?parent=8703"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/product_brand?post=8703"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/product_cat?post=8703"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.plantopia.me\/ar\/wp-json\/wp\/v2\/product_tag?post=8703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}